{"id":4564,"date":"2021-10-04T10:08:14","date_gmt":"2021-10-04T08:08:14","guid":{"rendered":"https:\/\/zank.de\/hilfe-bei\/internationales-sorgerecht\/"},"modified":"2022-01-28T16:52:46","modified_gmt":"2022-01-28T15:52:46","slug":"autorite-parentale-internationale","status":"publish","type":"page","link":"https:\/\/zank.de\/fr\/notre-soutien-dans-les-cas-suivants\/autorite-parentale-internationale\/","title":{"rendered":"Autorit\u00e9 parentale (droit de garde de l\u2019enfant) internationale"},"content":{"rendered":"\n<div class=\"wp-block-group alignfull intro-background is-layout-constrained wp-block-group-is-layout-constrained\"><div class=\"breadcrumb page-breadcrumb\"><span><a href=\"https:\/\/zank.de\/fr\/\"><span class=\"visually-hidden\">Go to homepage<\/span><svg class=\"icon icon-home\"><use href=\"#home\" \/><\/svg><\/a><\/span><\/div><h1 class=\"entry-title mt-0\">Autorit\u00e9 parentale (droit de garde de l\u2019enfant) internationale<\/h1>\n\n\n<p class=\"has-lead-font-size wp-block-paragraph\"><em>Des relations familiales avec plus d\u2019un pays peuvent \u00eatre la source d\u2019inqui\u00e9tudes et d\u2019incertitudes quand \u00e0 l\u2019autorit\u00e9 parentale\/le droit de garde de l\u2019enfant. Avez-vous la garde conjointe ? L\u2019un des parents (ou un tuteur) a-t-il le droit de garde exclusif ? L\u2019autorit\u00e9 parentale est-elle soumise partout aux m\u00eames r\u00e8glementations ? En r\u00e9alit\u00e9, les r\u00e8glementations sur l\u2019autorit\u00e9 parentale et le droit de garde sont diff\u00e9rentes dans de nombreux pays. Nous vous indiquons ci-apr\u00e8s les modalit\u00e9s d\u2019autorit\u00e9 parentale en d\u00e9tail.<\/em><\/p>\n\n\n\n<ul class=\"is-style-anchor wp-block-list\"><li><a href=\"#conseille\">Qui conseille en mati\u00e8re d\u2019autorit\u00e9 parentale et de garde de l\u2019enfant<\/a><\/li><li><a href=\"#parentale\">Autorit\u00e9 parentale en Allemagne<\/a><\/li><li><a href=\"#autres-pays\">Autorit\u00e9 parentale dans d\u2019autres pays<\/a><\/li><li><a href=\"#reglementation\">Quelle est la r\u00e8glementation en vigueur pour l\u2019autorit\u00e9 parentale ?<\/a><\/li><li><a href=\"#decision-judiciaire\">Une d\u00e9cision judiciaire sur le droit de garde est-elle reconnue \u00e0 l\u2019\u00e9tranger ?<\/a><\/li><\/ul>\n<\/div>\n\n\n\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<h2 class=\"is-style-heading-h2 wp-block-heading\" id=\"conseille\"><strong>Qui conseille en mati\u00e8re d\u2019autorit\u00e9 parentale et de garde de l\u2019enfant<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Des informations relatives \u00e0 l\u2019autorit\u00e9 parentale et \u00e0 la garde de l\u2019enfant dans un autre pays vous seront donn\u00e9es par les <strong>autorit\u00e9s de ce pays<\/strong>, par le Bundesamt f\u00fcr Justiz (l\u2019Office f\u00e9d\u00e9ral de la justice) en tant qu\u2019<strong>Autorit\u00e9 centrale pour les conflits internationaux en mati\u00e8re de garde d\u2019enfants, <\/strong>&nbsp;ou par la repr\u00e9sentation consulaire comp\u00e9tente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour toutes questions sur l\u2019autorit\u00e9 parentale et la garde de l\u2019enfant en Allemagne, votre <strong>Jugendamt (service d\u2019aide \u00e0 l\u2019enfance et \u00e0 la jeunesse)<\/strong> pourra vous conseiller. Les <strong>centres de conseil \u00e0 but non lucratif&nbsp; ou confessionnels <\/strong>sont souvent \u00e9galement de bons interlocuteurs.<\/p>\n\n\n\n<div class=\"wp-block-group is-style-infobox is-layout-flow wp-block-group-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Quand il s\u2019agit en particulier de savoir quelles incidences vos relations familiales dans plus d\u2019un pays auront pour vous en mati\u00e8re d\u2019autorit\u00e9 parentale, prenez contact avec nous. Nous vous aiderons \u00e0 clarifier les points correspondants.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link\" href=\"https:\/\/zank.de\/fr\/contact-comment-nous-consulter\/\">Notre service de conseil<\/a><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-theme-spacer\" style=\"height:3.5rem\"><\/div>\n\n\n\n<h2 class=\"is-style-heading-h2 wp-block-heading\" id=\"parentale\"><strong>Autorit\u00e9 parentale en Allemagne<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Dans le droit familial allemand, l\u2019autorit\u00e9 parentale est r\u00e9gl\u00e9e diff\u00e9remment selon que vous \u00eates <strong>mari\u00e9s ensemble<\/strong> ou non.<\/p>\n\n\n\n<div class=\"wp-block-theme-accordion accordion-item\"><h3 class=\"accordion-header\" id=\"heading-e5703c7e-cacb-4868-9c51-f942d34f90b5\"><button class=\"accordion-button collapsed\" type=\"button\" aria-expanded=\"false\" aria-controls=\"collapse-e5703c7e-cacb-4868-9c51-f942d34f90b5\"><span class=\"accordion-button-text\">La garde exclusive ou conjointe ?<\/span><\/button><\/h3><div id=\"collapse-e5703c7e-cacb-4868-9c51-f942d34f90b5\" class=\"accordion-collapse collapse\" aria-labelledby=\"heading-e5703c7e-cacb-4868-9c51-f942d34f90b5\"><div class=\"accordion-body\">\n<p class=\"wp-block-paragraph\">Quand les parents, en Allemagne, ont-ils ou obtiennent-ils la garde conjointe ? Si vous \u00eates mari\u00e9s ensemble, en Allemagne, <strong>vous exercez la garde conjointe pour votre enfant<\/strong>. Toutes les questions importantes sont d\u00e9cid\u00e9es en commun. Ceci <strong>est maintenu \u00e9galement sous cette forme apr\u00e8s une s\u00e9paration ou un divorce<\/strong>. Ceci ne change que si l\u2019un des parents d\u00e9pose une demande correspondante aupr\u00e8s du Juge aux affaires familiales (Jaf) et s\u2019il y a de bonnes raisons \u00e0 cela. Le fait que les parents vivent dans des lieux diff\u00e9rents n\u2019est en g\u00e9n\u00e9ral pas consid\u00e9r\u00e9 comme une raison de lever le droit de garde conjoint.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Dans le cas de parents non mari\u00e9s ensemble<\/strong>, la situation juridique est telle que c\u2019est tout d\u2019abord la m\u00e8re qui exerce la garde exclusive, jusqu\u2019\u00e0 ce que les parents s\u2019entendent ensemble sur ce que l\u2019on fasse une <strong>d\u00e9claration de garde conjointe<\/strong>. Cette d\u00e9claration, par laquelle ils d\u00e9clarent vouloir exercer la garde conjointe, peut \u00eatre faite <strong>aupr\u00e8s du Jugendamt (le service d\u2019aide \u00e0 l\u2019enfance et \u00e0 la jeunesse)<\/strong> avant m\u00eame la naissance de l\u2019enfant. Si les (futurs) parents ne sont pas d\u2019accord, le p\u00e8re peut d\u00e9poser <strong>aupr\u00e8s du Juge aux affaires familiales (Jaf) une demande<\/strong> de garde conjointe. Cette demande sera accept\u00e9e \u2013 souvent dans le cadre d\u2019une proc\u00e9dure simplifi\u00e9e \u2013 \u00e0 condition que la garde conjointe ne s\u2019oppose pas, du point de vue du Juge aux affaires familiales (Jaf), aux int\u00e9r\u00eats et au bien de l\u2019enfant.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mais que se passe-t-il si, apr\u00e8s une s\u00e9paration, le couple ne parvient pas \u00e0 continuer de s\u2019entendre sur des d\u00e9cisions concernant leur enfant ? Dans ce cas, le Juge aux affaires familiales (Jaf) peut d\u00e9cider que <strong>la garde ne soit confi\u00e9e qu\u2019\u00e0 l\u2019un des parents<\/strong>. Le droit de visite et d\u2019h\u00e9bergement prend alors une importance particuli\u00e8re. Car m\u00eame si l\u2019un des parents a le droit de garde exclusif, un enfant a le droit d\u2019avoir des relations personnelles avec l\u2019autre parent.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vous trouverez ici des informations plus compl\u00e8tes sur le <a href=\"https:\/\/zank.de\/fr\/notre-soutien-dans-les-cas-suivants\/droit-de-visite-et-dhebergement\/\">Droit de maintien de relations personnelles et droit de visite et d\u2019h\u00e9bergement.<\/a><\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-theme-accordion accordion-item\"><h3 class=\"accordion-header\" id=\"heading-a4dc07c3-1ad8-4a57-b77a-ffdb3dc833cf\"><button class=\"accordion-button collapsed\" type=\"button\" aria-expanded=\"false\" aria-controls=\"collapse-a4dc07c3-1ad8-4a57-b77a-ffdb3dc833cf\"><span class=\"accordion-button-text\">Quels sont les points r\u00e9glement\u00e9s en Allemagne par le droit de garde ?<\/span><\/button><\/h3><div id=\"collapse-a4dc07c3-1ad8-4a57-b77a-ffdb3dc833cf\" class=\"accordion-collapse collapse\" aria-labelledby=\"heading-a4dc07c3-1ad8-4a57-b77a-ffdb3dc833cf\"><div class=\"accordion-body\">\n<p class=\"wp-block-paragraph\">Le droit de garde implique pour les parents <strong>le devoir et le droit<\/strong> de s\u2019occuper de leur enfant mineur. L\u2019autorit\u00e9 parentale implique en particulier :<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>le choix du nom de l\u2019enfant,<\/li><li>le choix de et l\u2019inscription \u00e0 une garderie, l\u2019\u00e9cole maternelle ou une \u00e9cole,<\/li><li>les d\u00e9cisions relatives \u00e0 l\u2019\u00e9ducation et la religion,<\/li><li>les traitements m\u00e9dicaux,<\/li><li>le droit de d\u00e9terminer le domicile de l\u2019enfant.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Le <strong>droit allemand permet un partage de l\u2019autorit\u00e9 parentale<\/strong>. Ceci signifie qu\u2019un Juge aux affaires familiales (Jaf) peut confier \u00e0 l\u2019un des parents le pouvoir de d\u00e9cision exclusif dans le cadre d\u2019une question concr\u00e8te. Ainsi par exemple, il est possible que, m\u00eame en cas de garde conjointe, le droit de d\u00e9terminer le domicile de l\u2019enfant soit confi\u00e9 seulement \u00e0 la m\u00e8re, ou seulement au p\u00e8re, ou seulement \u00e0 un tuteur. Dans ce cas exceptionnel, le domicile de l&#8217;enfant peut \u00eatre d\u00e9cid\u00e9 par l\u2019un des parents seul, sans l&#8217;accord de l&#8217;autre.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>La notion allemande du droit de garde n\u2019est pas transposable \u2013 sur le plan juridique et culturel, il existe dans le monde entier de grandes diff\u00e9rences selon les pays. N\u2019h\u00e9sitez pas \u00e0 vous adresser \u00e0 nous.<\/p><\/blockquote>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link\" href=\"https:\/\/zank.de\/fr\/contact-comment-nous-consulter\/\">Prendre contact avec nous<\/a><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-theme-spacer\" style=\"height:3.5rem\"><\/div>\n\n\n\n<h2 class=\"is-style-heading-h2 wp-block-heading\" id=\"autres-pays\"><strong>Autorit\u00e9 parentale dans d\u2019autres pays<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Il existe des diff\u00e9rences entre les pays en ce qui concerne le droit de garde en terme de terminologie (on l\u2019appelle par exemple&nbsp; \u00ab responsabilit\u00e9 parentale \u00bb) ainsi que l\u2019ampleur des droits qui en r\u00e9sultent (les d\u00e9cisions que l\u2019un des parents peut prendre seul).<\/p>\n\n\n\n<div class=\"wp-block-theme-accordion accordion-item\"><h3 class=\"accordion-header\" id=\"heading-5c0f3646-e3af-43b7-b432-44eef3c12631\"><button class=\"accordion-button collapsed\" type=\"button\" aria-expanded=\"false\" aria-controls=\"collapse-5c0f3646-e3af-43b7-b432-44eef3c12631\"><span class=\"accordion-button-text\">La garde exclusive ou conjointe ?<\/span><\/button><\/h3><div id=\"collapse-5c0f3646-e3af-43b7-b432-44eef3c12631\" class=\"accordion-collapse collapse\" aria-labelledby=\"heading-5c0f3646-e3af-43b7-b432-44eef3c12631\"><div class=\"accordion-body\">\n<p class=\"wp-block-paragraph\">Dans certains pays, au contraire de l\u2019Allemagne, le fait que les parents soient mari\u00e9s ensemble ou non n\u2019a pas d\u2019incidence : l\u2019<strong>autorit\u00e9 parentale<\/strong> (souvent appel\u00e9e <strong>\u00ab responsabilit\u00e9 parentale \u00bb<\/strong>) conjointe est donn\u00e9e par principe dans ces pays, m\u00eame pour les enfants dont <strong>les parents ne sont pas mari\u00e9s ensemble<\/strong>.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-theme-accordion accordion-item\"><h3 class=\"accordion-header\" id=\"heading-29ea0edc-3d07-46d0-83cb-0e90864637c8\"><button class=\"accordion-button collapsed\" type=\"button\" aria-expanded=\"false\" aria-controls=\"collapse-29ea0edc-3d07-46d0-83cb-0e90864637c8\"><span class=\"accordion-button-text\">Quels sont les droits qui sont li\u00e9s \u00e0 l\u2019autorit\u00e9 parentale ou la responsabilit\u00e9 parentale dans d\u2019autres pays ?<\/span><\/button><\/h3><div id=\"collapse-29ea0edc-3d07-46d0-83cb-0e90864637c8\" class=\"accordion-collapse collapse\" aria-labelledby=\"heading-29ea0edc-3d07-46d0-83cb-0e90864637c8\"><div class=\"accordion-body\">\n<p class=\"wp-block-paragraph\">Les r\u00e8glementations l\u00e9gales sur l\u2019autorit\u00e9 parentale sont tr\u00e8s diff\u00e9rentes selon les pays. Aussi, les droits et devoirs de chaque parent ne peuvent souvent \u00eatre d\u00e9termin\u00e9s qu\u2019au cas par cas, mais toujours de mani\u00e8re <strong>sp\u00e9cifique en fonction du pays<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Des diff\u00e9rences fr\u00e9quentes concernent l\u2019ampleur des droits associ\u00e9s \u00e0 l\u2019autorit\u00e9 parentale ou la responsabilit\u00e9 parentale :<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Si par exemple un enfant vit seulement avec sa m\u00e8re ou seulement avec son p\u00e8re, celui-ci ou celle-ci, dans de nombreux pays ne peut &#8211; m\u00eame avec <strong>l\u2019autorit\u00e9 parentale exclusive<\/strong> \u2013 r\u00e9gler seul que certaines <strong>questions de la vie quotidienne<\/strong>. Toute d\u00e9cision fondamentale, comme le d\u00e9part \u00e0 l\u2019\u00e9tranger avec l\u2019enfant, n\u00e9cessite l\u2019accord de l\u2019autre parent. Ceci est \u00e9galement le cas si celui-ci ne vit pas avec l\u2019enfant et ne jouit pas du droit de d\u00e9terminer le domicile de l\u2019enfant ou d\u2019exercer l\u2019autorit\u00e9 parentale. Dans certains pays, ceci s\u2019applique \u00e9galement \u00e0 de brefs voyages de vacances.<\/li><li>Dans de nombreux <strong>ordres juridiques arabes<\/strong>, l\u2019autorit\u00e9 parentale comprend la garde r\u00e9elle d\u2019un enfant (hadana), mais pas toutefois sa repr\u00e9sentation juridique ou tutelle (wilaya). La premi\u00e8re est en g\u00e9n\u00e9rale exerc\u00e9e par la m\u00e8re (ou une femme de la famille), la deuxi\u00e8me par le p\u00e8re (ou un homme de la famille). Le tuteur surveille les soins apport\u00e9s \u00e0 l\u2019enfant et d\u00e9cide donc du domicile de l\u2019enfant.<\/li><\/ul>\n<\/div><\/div><\/div>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><em>Dans le cas de l\u2019autorit\u00e9 parentale conjointe, aucun des deux parents n\u2019a le droit de d\u00e9cider du domicile de l\u2019enfant sans l\u2019accord de l\u2019autre parent. Dans de nombreux pays, ceci est valable ind\u00e9pendamment de qui exerce l\u2019autorit\u00e9 parentale.<\/em><\/p><\/blockquote>\n\n\n\n<h2 class=\"is-style-heading-h2 wp-block-heading\" id=\"reglementation\"><strong>Quelle est la r\u00e8glementation en vigueur pour l\u2019autorit\u00e9 parentale ?<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La question de savoir quelles sont les <strong>r\u00e8glementations nationales sp\u00e9cifiques<\/strong> qui s\u2019appliquent \u00e0 vous et votre famille en mati\u00e8re d\u2019autorit\u00e9 parentale se pose en particulier si votre enfant a v\u00e9cu dans plus d\u2019un seul pays.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Ce qui compte est tout d\u2019abord le lieu de r\u00e9sidence habituelle.<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">WelLa loi applicable pour votre enfant d\u00e9pend concr\u00e8tement du pays de <strong>r\u00e9sidence habituelle<\/strong> actuelle de l\u2019enfant. Ceci signifie que si le centre des int\u00e9r\u00eats vitaux de votre enfant est en Allemagne, c\u2019est \u2013 <strong>ind\u00e9pendamment du domicile des parents et de la nationalit\u00e9 de l\u2019enfant <\/strong>\u2013 le droit allemand qui s\u2019applique. \u00c0 l\u2019inverse, si votre enfant de nationalit\u00e9 allemande vit <em>habituellement<\/em> par exemple en Espagne, c\u2019est le droit espagnol en mati\u00e8re de responsabilit\u00e9 parentale qui est applicable.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Toutefois, la Convention de La Haye sur la responsabilit\u00e9 parentale et la protection des enfants pr\u00e9voit dans ce contexte une particularit\u00e9 : en cas de changement du lieu de r\u00e9sidence habituel, c\u2019est-\u00e0-dire d\u2019un d\u00e9m\u00e9nagement \u00e0 destination d\u2019un autre pays, il est possible <strong>d\u2019acqu\u00e9rir de nouveaux droits<\/strong> parentaux si ceux-ci sont pr\u00e9vus par la loi de ce pays.&nbsp; Mais des droits acquis <strong>ne peuvent plus \u00eatre retir\u00e9s<\/strong>. Ils sont emport\u00e9s partout comme dans un sac \u00e0 dos.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Pour r\u00e9gler des questions d\u2019autorit\u00e9 parentale, c\u2019est le droit du lieu de r\u00e9sidence habituelle qui est applicable ; en m\u00eame temps, tous droits parentaux \u00ab apport\u00e9s \u00bb doivent \u00eatre pris en compte et continuent d\u2019\u00eatre valables.<\/p><\/blockquote>\n\n\n\n<div class=\"wp-block-group is-style-infobox is-layout-flow wp-block-group-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong>Exemple : <\/strong>Un couple non mari\u00e9 quitte l\u2019Allemagne avec son enfant pour aller habiter pour une p\u00e9riode prolong\u00e9e ou d\u00e9finitivement dans un autre pays. Dans ce pays, l\u2019autorit\u00e9 parentale conjointe est pr\u00e9vue aussi pour les enfants de parents non mari\u00e9s. Le p\u00e8re acquiert alors, m\u00eame sans avoir fait une d\u00e9claration pr\u00e9alable de garde conjointe en accord avec la m\u00e8re, le droit \u00e0 la garde conjointe.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ceci signifie premi\u00e8rement que, de par la nouvelle r\u00e9sidence principale de l\u2019enfant et les lois qui y sont en vigueur, le r\u00e8glement de l\u2019autorit\u00e9 parentale a chang\u00e9. Si, plus tard, l\u2019un des parents devait souhaiter d\u00e9m\u00e9nager une nouvelle fois dans un autre pays avec l\u2019enfant, ceci ne serait possible que si les deux parents sont d\u2019accord sur ce point.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mais ceci signifie deuxi\u00e8mement aussi que si le couple et l\u2019enfant reviennent un jour ensemble en Allemagne, le droit \u00e0 l\u2019autorit\u00e9 parentale commune acquis \u00e0 l\u2019\u00e9tranger de par la l\u00e9gislation en vigueur dans l\u2019autre pays restera applicable.<\/p>\n<\/div>\n\n\n\n<h2 class=\"is-style-heading-h2 wp-block-heading\" id=\"decision-judiciaire\"><strong><strong>Une d\u00e9cision judiciaire sur le droit de garde est-elle reconnue \u00e0 l\u2019\u00e9tranger ?<\/strong><\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Parfois, les conflits relatifs \u00e0 la garde de l\u2019enfant doivent \u00eatre tranch\u00e9s par les tribunaux. En cas de composante internationale, il peut \u00eatre important de savoir si une d\u00e9cision d\u2019un Juge aux affaires familiales (Jaf) d\u2019un pays est <strong>reconnue dans l\u2019autre pays<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vous vous inqui\u00e9tez de savoir si une d\u00e9cision judiciaire sera valable avec certitude \u00e9galement par-del\u00e0 les fronti\u00e8res ? Il est effectivement souvent difficile de pr\u00e9voir et de savoir si et dans quelles conditions ce sera le cas.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Les d\u00e9cisions de tribunaux \u00e9trangers peuvent certes \u00eatre reconnues dans le monde entier, mais pour la plupart des cas, des proc\u00e9dures sp\u00e9ciales sont n\u00e9cessaires pour cela.<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">C&#8217;est un peu plus facile au sein de l\u2019Union europ\u00e9enne (UE) et lorsqu\u2019il existe des conventions entre les pays.<\/p>\n\n\n\n<div class=\"wp-block-theme-accordion accordion-item\"><h3 class=\"accordion-header\" id=\"heading-06db6c1b-99a5-488d-8deb-ed1a7936ae0d\"><button class=\"accordion-button collapsed\" type=\"button\" aria-expanded=\"false\" aria-controls=\"collapse-06db6c1b-99a5-488d-8deb-ed1a7936ae0d\"><span class=\"accordion-button-text\">Informations compl\u00e9mentaires relatives \u00e0 la reconnaissance de d\u00e9cisions judiciaires au sein de l\u2019UE et entre des \u00c9tats contractants \u00e0 la Convention de La Haye sur la responsabilit\u00e9 parentale et la protection des enfants<\/span><\/button><\/h3><div id=\"collapse-06db6c1b-99a5-488d-8deb-ed1a7936ae0d\" class=\"accordion-collapse collapse\" aria-labelledby=\"heading-06db6c1b-99a5-488d-8deb-ed1a7936ae0d\"><div class=\"accordion-body\">\n<p class=\"wp-block-paragraph\">Les r\u00e8glements internationaux, en particulier le R\u00e8glement europ\u00e9en Bruxelles II bis et, dans certains cas, la Convention europ\u00e9enne sur la reconnaissance et l\u2019ex\u00e9cution des d\u00e9cisions en mati\u00e8re de garde des enfants ainsi que la Convention de La Haye sur la responsabilit\u00e9 parentale et la protection des enfants, ont <strong>simplifi\u00e9 la reconnaissance et l&#8217;ex\u00e9cution des d\u00e9cisions des tribunaux aux affaires familiales dans l\u2019autre pays<\/strong>, tout au moins entre les \u00c9tats membres ou contractants concern\u00e9s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alors que les d\u00e9cisions des tribunaux aux affaires familiales d&#8217;un \u00c9tat membre de l&#8217;UE ou d&#8217;un \u00c9tat contractant sont valables <strong>en vertu de la loi<\/strong> dans tous les autres (\u00e0 l&#8217;exception du Danemark), toute instance \u00e0 laquelle elles sont pr\u00e9sent\u00e9es <strong>examinera<\/strong> (doit examiner) \u00e0 nouveau <strong>au cas par cas<\/strong> s&#8217;il existe des motifs fondant un refus de reconnaissance. La reconnaissance au-del\u00e0 de certains organismes devient contraignante<strong> par une constatation judiciaire<\/strong>. Celle-ci doit \u00eatre demand\u00e9e aupr\u00e8s du tribunal comp\u00e9tent du pays dans lequel la d\u00e9cision doit \u00eatre reconnue. Les <strong>Autorit\u00e9s centrales<\/strong> peuvent ici apporter leur aide.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Pour trouver un interlocuteur en ce qui concerne la reconnaissance ou l\u2019ex\u00e9cution d\u2019une d\u00e9cision judiciaire, vous pouvez utiliser notre <a href=\"https:\/\/zank.de\/en\/materials-addresses\/contacts\/\">r\u00e9pertoire d\u2019adresses<\/a>.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignfull has-primary-light-background-color has-background is-layout-constrained wp-container-core-group-is-layout-38fc762d wp-block-group-is-layout-constrained\" style=\"padding-top:70px;padding-bottom:70px\">\n<div class=\"wp-block-columns is-style-default is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-style-card is-layout-flow wp-block-group-is-layout-flow\" style=\"padding-top:26px\">\n<h3 class=\"wp-block-heading\" style=\"margin-bottom:15px\">Contact<\/h3>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link\" href=\"https:\/\/zank.de\/fr\/contact-comment-nous-consulter\/\">Service conseil<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-style-card is-layout-flow wp-block-group-is-layout-flow\" style=\"padding-top:26px\">\n<h3 class=\"wp-block-heading\" style=\"margin-bottom:15px\">\u00c9tablissement de r\u00e8glementations<\/h3>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link\" href=\"https:\/\/zank.de\/fr\/notre-soutien-dans-les-cas-suivants\/droit-de-visite-et-dhebergement\/\">Droit de visite et d\u2019h\u00e9bergement<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-style-card is-layout-flow wp-block-group-is-layout-flow\" style=\"padding-top:26px\">\n<h3 class=\"wp-block-heading\" style=\"margin-bottom:15px\">Trouver un interlocuteur<\/h3>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link\" href=\"https:\/\/zank.de\/en\/materials-addresses\/contacts\/\">R\u00e9pertoire d\u2019adresses<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Des relations familiales avec plus d\u2019un pays peuvent \u00eatre la source d\u2019inqui\u00e9tudes et d\u2019incertitudes quand \u00e0 l\u2019autorit\u00e9 parentale\/le droit de garde de l\u2019enfant. Avez-vous la garde conjointe ? L\u2019un des parents (ou un tuteur) a-t-il le droit de garde exclusif ? L\u2019autorit\u00e9 parentale est-elle soumise partout aux m\u00eames r\u00e8glementations ? En r\u00e9alit\u00e9, les r\u00e8glementations sur [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":4558,"menu_order":1,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-4564","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Autorit\u00e9 parentale (droit de garde de l\u2019enfant) internationale &#8226; ZAnK<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zank.de\/fr\/notre-soutien-dans-les-cas-suivants\/autorite-parentale-internationale\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Autorit\u00e9 parentale (droit de garde de l\u2019enfant) internationale &#8226; ZAnK\" \/>\n<meta property=\"og:description\" content=\"Des relations familiales avec plus d\u2019un pays peuvent \u00eatre la source d\u2019inqui\u00e9tudes et d\u2019incertitudes quand \u00e0 l\u2019autorit\u00e9 parentale\/le droit de garde de l\u2019enfant. Avez-vous la garde conjointe ? L\u2019un des parents (ou un tuteur) a-t-il le droit de garde exclusif ? L\u2019autorit\u00e9 parentale est-elle soumise partout aux m\u00eames r\u00e8glementations ? En r\u00e9alit\u00e9, les r\u00e8glementations sur [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zank.de\/fr\/notre-soutien-dans-les-cas-suivants\/autorite-parentale-internationale\/\" \/>\n<meta property=\"og:site_name\" content=\"ZAnK\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-28T15:52:46+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/zank.de\\\/fr\\\/notre-soutien-dans-les-cas-suivants\\\/autorite-parentale-internationale\\\/\",\"url\":\"https:\\\/\\\/zank.de\\\/fr\\\/notre-soutien-dans-les-cas-suivants\\\/autorite-parentale-internationale\\\/\",\"name\":\"Autorit\u00e9 parentale (droit de garde de l\u2019enfant) internationale &#8226; ZAnK\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zank.de\\\/#website\"},\"datePublished\":\"2021-10-04T08:08:14+00:00\",\"dateModified\":\"2022-01-28T15:52:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zank.de\\\/fr\\\/notre-soutien-dans-les-cas-suivants\\\/autorite-parentale-internationale\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/zank.de\\\/fr\\\/notre-soutien-dans-les-cas-suivants\\\/autorite-parentale-internationale\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zank.de\\\/fr\\\/notre-soutien-dans-les-cas-suivants\\\/autorite-parentale-internationale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/zank.de\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Notre soutien dans les cas suivants \u2026\",\"item\":\"https:\\\/\\\/zank.de\\\/fr\\\/notre-soutien-dans-les-cas-suivants\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Autorit\u00e9 parentale (droit de garde de l\u2019enfant) internationale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zank.de\\\/#website\",\"url\":\"https:\\\/\\\/zank.de\\\/\",\"name\":\"ZAnK\",\"description\":\"Zentrale Anlaufstelle f\u00fcr grenz\u00fcberschreitende Kindschaftskonflikte und Mediation\",\"publisher\":{\"@id\":\"https:\\\/\\\/zank.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zank.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/zank.de\\\/#organization\",\"name\":\"ZAnK\",\"url\":\"https:\\\/\\\/zank.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/zank.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/zank.de\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/ZANK_Logo.svg\",\"contentUrl\":\"https:\\\/\\\/zank.de\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/ZANK_Logo.svg\",\"width\":567,\"height\":172,\"caption\":\"ZAnK\"},\"image\":{\"@id\":\"https:\\\/\\\/zank.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Autorit\u00e9 parentale (droit de garde de l\u2019enfant) internationale &#8226; ZAnK","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zank.de\/fr\/notre-soutien-dans-les-cas-suivants\/autorite-parentale-internationale\/","og_locale":"fr_FR","og_type":"article","og_title":"Autorit\u00e9 parentale (droit de garde de l\u2019enfant) internationale &#8226; ZAnK","og_description":"Des relations familiales avec plus d\u2019un pays peuvent \u00eatre la source d\u2019inqui\u00e9tudes et d\u2019incertitudes quand \u00e0 l\u2019autorit\u00e9 parentale\/le droit de garde de l\u2019enfant. Avez-vous la garde conjointe ? L\u2019un des parents (ou un tuteur) a-t-il le droit de garde exclusif ? L\u2019autorit\u00e9 parentale est-elle soumise partout aux m\u00eames r\u00e8glementations ? En r\u00e9alit\u00e9, les r\u00e8glementations sur [&hellip;]","og_url":"https:\/\/zank.de\/fr\/notre-soutien-dans-les-cas-suivants\/autorite-parentale-internationale\/","og_site_name":"ZAnK","article_modified_time":"2022-01-28T15:52:46+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"11 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/zank.de\/fr\/notre-soutien-dans-les-cas-suivants\/autorite-parentale-internationale\/","url":"https:\/\/zank.de\/fr\/notre-soutien-dans-les-cas-suivants\/autorite-parentale-internationale\/","name":"Autorit\u00e9 parentale (droit de garde de l\u2019enfant) internationale &#8226; ZAnK","isPartOf":{"@id":"https:\/\/zank.de\/#website"},"datePublished":"2021-10-04T08:08:14+00:00","dateModified":"2022-01-28T15:52:46+00:00","breadcrumb":{"@id":"https:\/\/zank.de\/fr\/notre-soutien-dans-les-cas-suivants\/autorite-parentale-internationale\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/zank.de\/fr\/notre-soutien-dans-les-cas-suivants\/autorite-parentale-internationale\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/zank.de\/fr\/notre-soutien-dans-les-cas-suivants\/autorite-parentale-internationale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/zank.de\/fr\/"},{"@type":"ListItem","position":2,"name":"Notre soutien dans les cas suivants \u2026","item":"https:\/\/zank.de\/fr\/notre-soutien-dans-les-cas-suivants\/"},{"@type":"ListItem","position":3,"name":"Autorit\u00e9 parentale (droit de garde de l\u2019enfant) internationale"}]},{"@type":"WebSite","@id":"https:\/\/zank.de\/#website","url":"https:\/\/zank.de\/","name":"ZAnK","description":"Zentrale Anlaufstelle f\u00fcr grenz\u00fcberschreitende Kindschaftskonflikte und Mediation","publisher":{"@id":"https:\/\/zank.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zank.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/zank.de\/#organization","name":"ZAnK","url":"https:\/\/zank.de\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/zank.de\/#\/schema\/logo\/image\/","url":"https:\/\/zank.de\/wp-content\/uploads\/2021\/10\/ZANK_Logo.svg","contentUrl":"https:\/\/zank.de\/wp-content\/uploads\/2021\/10\/ZANK_Logo.svg","width":567,"height":172,"caption":"ZAnK"},"image":{"@id":"https:\/\/zank.de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/zank.de\/fr\/wp-json\/wp\/v2\/pages\/4564","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zank.de\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/zank.de\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/zank.de\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zank.de\/fr\/wp-json\/wp\/v2\/comments?post=4564"}],"version-history":[{"count":7,"href":"https:\/\/zank.de\/fr\/wp-json\/wp\/v2\/pages\/4564\/revisions"}],"predecessor-version":[{"id":4722,"href":"https:\/\/zank.de\/fr\/wp-json\/wp\/v2\/pages\/4564\/revisions\/4722"}],"up":[{"embeddable":true,"href":"https:\/\/zank.de\/fr\/wp-json\/wp\/v2\/pages\/4558"}],"wp:attachment":[{"href":"https:\/\/zank.de\/fr\/wp-json\/wp\/v2\/media?parent=4564"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}