{"id":4757,"date":"2021-10-04T10:08:18","date_gmt":"2021-10-04T08:08:18","guid":{"rendered":"https:\/\/zank.de\/ayuda-con\/recht-auf-umgang\/"},"modified":"2022-03-02T14:20:03","modified_gmt":"2022-03-02T13:20:03","slug":"derecho-de-acceso","status":"publish","type":"page","link":"https:\/\/zank.de\/es\/ayuda-con\/derecho-de-acceso\/","title":{"rendered":"Derecho de acceso"},"content":{"rendered":"\n<div class=\"wp-block-group alignfull intro-background is-layout-constrained wp-block-group-is-layout-constrained\"><div class=\"breadcrumb page-breadcrumb\"><span><a href=\"https:\/\/zank.de\/es\/\"><span class=\"visually-hidden\">Go to homepage<\/span><svg class=\"icon icon-home\"><use href=\"#home\" \/><\/svg><\/a><\/span><\/div><h1 class=\"entry-title mt-0\">Derecho de acceso<\/h1>\n\n\n<p class=\"has-lead-font-size wp-block-paragraph\">Los ni\u00f1os tienen derecho a tener contacto con ambos padres. Por el contrario, ambos progenitores tienen el derecho -y el deber- fundamental de tener contacto con su hijo. El contacto se traduce en reuniones personales peri\u00f3dicas, as\u00ed como en contactos por carta y\/o por tel\u00e9fono. Un buen acuerdo de contacto puede dar al ni\u00f1o la sensaci\u00f3n de estar seguro en su familia incluso despu\u00e9s de que los padres se hayan separado o divorciado.<\/p>\n\n\n\n<ul class=\"is-style-anchor wp-block-list\"><li><a href=\"#contactar\">Qui\u00e9n tiene derecho a contactar<\/a><\/li><li><a href=\"#\"><\/a><a href=\"#transfronterizo\">Trato transfronterizo<\/a><\/li><li><a href=\"#contactos\">Posibilidades de aclarar un conflicto de contactos<\/a><\/li><\/ul>\n<\/div>\n\n\n\n<h2 class=\"is-style-heading-h2 wp-block-heading\" id=\"contactar\"><strong>Qui\u00e9n tiene derecho a contactar<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Mediante el <strong>contacto con el progenitor con el que no vive su hijo, <\/strong>este debe aprender que ese progenitor tambi\u00e9n est\u00e1 ah\u00ed y se preocupa por \u00e9l. Por regla general, todos los padres tienen derecho a ver a sus hijos<em>, <\/em>y ellos a sus padres. <strong>Solo se restringe si el bienestar del ni\u00f1o puede estar en peligro<\/strong>. Los abuelos y los hermanos, as\u00ed como otros cuidadores cercanos del ni\u00f1o que realmente tienen o han tenido la responsabilidad del ni\u00f1o, tambi\u00e9n pueden tener derecho de contacto.<\/p>\n\n\n\n<h2 class=\"is-style-heading-h2 wp-block-heading\" id=\"transfronterizo\"><strong>Trato transfronterizo<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Si el menor y el padre o la madre de contacto viven en pa\u00edses diferentes, suele ser m\u00e1s dif\u00edcil organizar el contacto de forma que funcione para todos. Cuando uno <strong>de los progenitores se traslada a otro pa\u00eds<\/strong>, es posible que el acuerdo de contacto practicado anteriormente ya no se adapte. Por ejemplo, el acuerdo generalizado en Alemania de verse cada dos fines de semana y un d\u00eda a la semana <strong>apenas es posible como antes<\/strong>. Uno de los padres tambi\u00e9n puede cuestionar la pr\u00e1ctica anterior.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hay que hacer <strong>nuevos arreglos.<\/strong> Las llamadas telef\u00f3nicas o el contacto a trav\u00e9s de Skype, pero tambi\u00e9n las visitas durante los periodos de vacaciones y los d\u00edas festivos, suelen cobrar mayor importancia.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00bfYa no vive en el mismo pa\u00eds que su hijo? En principio, esto no cambia el derecho que usted y su hijo tienen a un contacto regular.<\/p><\/blockquote>\n\n\n\n<h2 class=\"is-style-heading-h2 wp-block-heading\" id=\"contactos\"><strong>Posibilidades de aclarar un conflicto de contactos<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfQu\u00e9 pasa si ustedes<strong>, como padres, no est\u00e1n de acuerdo en cuestiones de contacto<\/strong>? Si se discute sobre c\u00f3mo se puede realizar el contacto de una manera respetuosa con el menor en vista de las fronteras nacionales que se encuentran entre ustedes, hay una <strong>amplia gama de formas <\/strong>de abordarlo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aunque un litigio parezca insoluble y los intereses parezcan demasiado opuestos, casi siempre recomendamos a las madres, padres y otras personas con derecho de visita a <strong>seguir recurriendo al asesoramiento <\/strong>y considerar diversos <strong>m\u00e9todos extrajudiciales de resoluci\u00f3n de conflictos para <\/strong>usted cuando haga valer su derecho de visita.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>La forma de imponer el contacto con su hijo a trav\u00e9s de las fronteras nacionales ante un conflicto con el otro progenitor solo puede responderse concretamente en casos individuales.<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">No hay soluciones generales. Por lo tanto, nuestro asesoramiento suele consistir en identificar diferentes enfoques y animarle a considerarlos, especialmente en relaci\u00f3n con el <strong>bienestar y el inter\u00e9s superior del ni\u00f1o en cuesti\u00f3n.<\/strong><\/p>\n\n\n\n<div class=\"wp-block-theme-accordion accordion-item\"><h3 class=\"accordion-header\" id=\"heading-a6ae75d9-d04d-4670-9556-59469f755900\"><button class=\"accordion-button collapsed\" type=\"button\" aria-expanded=\"false\" aria-controls=\"collapse-a6ae75d9-d04d-4670-9556-59469f755900\"><span class=\"accordion-button-text\">Utilizar los servicios de asesoramiento<\/span><\/button><\/h3><div id=\"collapse-a6ae75d9-d04d-4670-9556-59469f755900\" class=\"accordion-collapse collapse\" aria-labelledby=\"heading-a6ae75d9-d04d-4670-9556-59469f755900\"><div class=\"accordion-body\">\n<p class=\"wp-block-paragraph\">Si el ni\u00f1o tiene su residencia habitual en Alemania, ustedes como padres -individualmente o conjuntamente- pueden dirigirse a la <strong>Oficina de Asistencia a la Juventud <\/strong>o a otros <strong>centros de asesoramiento familiar.<\/strong> Aqu\u00ed se le ayudar\u00e1 gratuitamente a negociar una soluci\u00f3n adecuada a su situaci\u00f3n. Los padres que viven en el extranjero tambi\u00e9n tienen derecho a beneficiarse de este asesoramiento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si usted vive en Alemania pero su hijo vive con el otro progenitor en otro pa\u00eds, la Oficina Federal de Justicia le asesorar\u00e1 en su funci\u00f3n de autoridad central.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, nuestros asesores de ZAnK estar\u00e1n encantados de ayudarle.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link\" href=\"https:\/\/zank.de\/es\/contacto-su-camino-hacia-el-asesoramiento\/\">Contacto<\/a><\/div>\n<\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-theme-accordion accordion-item\"><h3 class=\"accordion-header\" id=\"heading-0d2ab088-80bc-4217-9a3f-8cd2a9e6398d\"><button class=\"accordion-button collapsed\" type=\"button\" aria-expanded=\"false\" aria-controls=\"collapse-0d2ab088-80bc-4217-9a3f-8cd2a9e6398d\"><span class=\"accordion-button-text\">Acuerdo extrajudicial<\/span><\/button><\/h3><div id=\"collapse-0d2ab088-80bc-4217-9a3f-8cd2a9e6398d\" class=\"accordion-collapse collapse\" aria-labelledby=\"heading-0d2ab088-80bc-4217-9a3f-8cd2a9e6398d\"><div class=\"accordion-body\">\n<p class=\"wp-block-paragraph\">Si intenta llegar a un acuerdo con el otro progenitor fuera de los tribunales, esto no significa necesariamente que est\u00e9 solo en la negociaci\u00f3n de una soluci\u00f3n adecuada. <strong>\u00bfQuiz\u00e1s pueda pedir ayuda a sus confidentes o incluso a terceros independientes? <\/strong>En algunas familias, implicar a otros miembros de la familia en la b\u00fasqueda de una soluci\u00f3n es lo m\u00e1s adecuado. En otras familias, el apoyo de un mediador es exactamente lo que se necesita para acercarse de nuevo a un acuerdo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n se <strong>anima a los tribunales de familia a promover <\/strong>un <strong>acuerdo de paternidad <\/strong>aprobado por el tribunal de forma prioritaria antes de emitir una orden de contacto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hemos recopilado m\u00e1s informaci\u00f3n sobre diversos m\u00e9todos de resoluci\u00f3n consensuada de conflictos.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link\" href=\"https:\/\/zank.de\/es\/sobre-nosotros\/quienes-somos\/\">Sobre los m\u00e9todos de resoluci\u00f3n consensuada de conflictos<\/a><\/div>\n<\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-theme-accordion accordion-item\"><h3 class=\"accordion-header\" id=\"heading-f9992ceb-b1d6-4ffd-b823-259f4b0e9496\"><button class=\"accordion-button collapsed\" type=\"button\" aria-expanded=\"false\" aria-controls=\"collapse-f9992ceb-b1d6-4ffd-b823-259f4b0e9496\"><span class=\"accordion-button-text\">Qu\u00e9 cuestiones de contacto son decididas por los tribunales<\/span><\/button><\/h3><div id=\"collapse-f9992ceb-b1d6-4ffd-b823-259f4b0e9496\" class=\"accordion-collapse collapse\" aria-labelledby=\"heading-f9992ceb-b1d6-4ffd-b823-259f4b0e9496\"><div class=\"accordion-body\">\n<p class=\"wp-block-paragraph\">La forma de iniciar la resoluci\u00f3n judicial de un litigio transfronterizo sobre el derecho de visita <strong>depende de varios factores:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>tanto si se trata de una nueva normativa como del reconocimiento y ejecuci\u00f3n de una orden judicial existente;<\/li><li>en qu\u00e9 pa\u00eds vive el ni\u00f1o;<\/li><li>en qu\u00e9 pa\u00eds vive el progenitor que quiere hacer valer su derecho de visita;<\/li><li>los acuerdos y reglamentos internacionales que se aplican entre estos pa\u00edses.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Este \u00faltimo punto es importante porque, adem\u00e1s de la <strong>legislaci\u00f3n europea, <\/strong>en Alemania intervienen varios <strong>convenios internacionales que prev\u00e9n la <\/strong>resoluci\u00f3n de conflictos transfronterizos en el \u00e1mbito familiar.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Nueva regulaci\u00f3n del contacto en el extranjero sobre la base del Convenio de La Haya sobre Sustracci\u00f3n de Menores<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Si <strong>usted es un progenitor que vive en Alemania <\/strong>y desea organizar el contacto con su hijo que vive en otro pa\u00eds, generalmente tiene derecho a iniciar <strong>un procedimiento en virtud del Convenio de La Haya sobre Sustracci\u00f3n de Menores.<\/strong> El requisito es que el pa\u00eds donde se encuentra su hijo sea tambi\u00e9n un Estado contratante. Usted presenta la <strong>solicitud a la Oficina Federal de Justicia<\/strong>. Como Autoridad Central en el sentido del Convenio para Alemania, la Oficina Federal transmite su solicitud a la respectiva Autoridad Central extranjera; en consecuencia, los tribunales o autoridades de ese pa\u00eds pueden determinar el derecho de visita.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si <strong>usted vive como progenitor en otro Estado contratante <\/strong>y desea que se regule el contacto con su hijo que vive en Alemania, p\u00f3ngase en contacto con la autoridad central de su pa\u00eds a la inversa. La Oficina Federal de Justicia tambi\u00e9n se ofrece a iniciar un procedimiento ante el tribunal alem\u00e1n competente en nombre de un solicitante.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>El Convenio de La Haya sobre Sustracci\u00f3n de Menores hace posible, por tanto, que un progenitor demande la regulaci\u00f3n del contacto en uno de los Estados contratantes en cualquier momento.<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, hay que tener en cuenta que el apoyo de las Autoridades Centrales y de los Tribunales a las solicitudes de contacto puede variar mucho de un pa\u00eds a otro debido a los diferentes puntos de vista jur\u00eddicos. La Oficina Federal de Justicia subraya que muchos otros Estados contratantes solo apoyar\u00edan los casos de esta disposici\u00f3n en los que se deba establecer el contacto tras una sustracci\u00f3n.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Ejecuci\u00f3n de una decisi\u00f3n sobre el derecho de visita en el extranjero<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Si ya existe una decisi\u00f3n judicial sobre el derecho de visita que debe aplicarse en el lugar donde vive su hijo, entran en juego otras <strong>bases jur\u00eddicas<\/strong>, seg\u00fan amerite la situaci\u00f3n. En los casos individuales, se trata del <strong>Reglamento Bruselas II bis de la Uni\u00f3n Europea<\/strong>, el <strong>Convenio de La Haya sobre la Protecci\u00f3n de los Ni\u00f1os<\/strong>, el <strong>Convenio Europeo sobre la Custodia <\/strong>o <strong>la legislaci\u00f3n nacional<\/strong>.<\/p>\n\n\n\n<div class=\"wp-block-group is-style-default is-layout-flow wp-block-group-is-layout-flow\">\n<p class=\"has-lead-font-size wp-block-paragraph\">Reconocimiento transfronterizo<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la Uni\u00f3n Europea (a excepci\u00f3n de Dinamarca), una decisi\u00f3n judicial sobre la custodia o el derecho de visita de un Estado miembro es <strong>reconocida por la ley <\/strong>en todos los dem\u00e1s. Este principio tambi\u00e9n se aplica <strong>entre los Estados contratantes <\/strong>del<strong> Convenio de La Haya sobre la protecci\u00f3n de los ni\u00f1os.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, tanto el Reglamento Europeo como el Convenio especifican los motivos por los que se puede denegar el reconocimiento, y estos son <strong>reexaminados en cada caso individual por <\/strong>cada autoridad que tenga una decisi\u00f3n extranjera. Puede contrarrestarlo haciendo que el <strong>reconocimiento de una decisi\u00f3n sea vinculante para un tribunal<\/strong>. Puede solicitarlo directamente en el pa\u00eds que debe reconocer una resoluci\u00f3n o en la Oficina Federal de Justicia o en la autoridad central del otro pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este \u00faltimo enfoque tambi\u00e9n es posible en relaci\u00f3n con Dinamarca, Islandia, Liechtenstein, la Antigua Rep\u00fablica Yugoslava de Macedonia del Norte, Moldavia, Montenegro, Noruega, Suiza, Serbia, Turqu\u00eda y Ucrania. La base jur\u00eddica se encuentra entonces en el <strong>Convenio Europeo de Custodia<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si se trata del <strong>reconocimiento de una resoluci\u00f3n judicial extranjera en <\/strong>Alemania y esta procede de un pa\u00eds en el que no se aplican las normas internacionales mencionadas, puede solicitar el reconocimiento de la resoluci\u00f3n <strong>con arreglo a la legislaci\u00f3n nacional.<\/strong><\/p>\n<\/div>\n\n\n\n<p class=\"has-lead-font-size wp-block-paragraph\">Ejecuci\u00f3n de decisiones extranjeras sobre el derecho de visita<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las posibilidades de las autoridades centrales extranjeras de prestar apoyo en la ejecuci\u00f3n de las decisiones de acceso suelen ser bastante limitadas. Los <strong>medios disponibles en <\/strong>cada pa\u00eds para ejecutar una orden de contacto que no ha sido cumplida por una de las partes del conflicto <strong>tambi\u00e9n var\u00edan mucho en algunos casos.<\/strong> Pero, \u00bfcu\u00e1l es el procedimiento general?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Si son padres que viven en diferentes Estados miembros de<strong> la Uni\u00f3n Europea (UE):<\/strong><\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>El Reglamento Bruselas II bis establece que una sentencia de contacto dictada en un Estado miembro se reconoce en otro y puede <strong>ejecutarse de la misma manera que una sentencia nacional.<\/strong><\/li><li>Para ello, la decisi\u00f3n subyacente debe cumplir ciertos <strong>requisitos<\/strong><\/li><li>Si no se cumplen y, por lo tanto, la ejecuci\u00f3n directa queda descartada, se puede iniciar un <strong>procedimiento de &#8220;declaraci\u00f3n de ejecuci\u00f3n&#8221;.<\/strong> Esto se lleva a cabo con la asistencia de un abogado local en el pa\u00eds donde se va a hacer valer el derecho de visita.<\/li><li>Las <strong>Autoridades Centrales asesoran a <\/strong>los padres que desean efectuar el reconocimiento\/la ejecuci\u00f3n.<\/li><\/ul>\n\n\n\n<div class=\"wp-block-theme-spacer\" style=\"height:1.2rem\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Si cada uno de ustedes, como padres, vive en Alemania y en otro Estado contratante del Convenio Europeo de Custodia o del Convenio de La Haya de Protecci\u00f3n de los Ni\u00f1os:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>El Convenio Europeo sobre la Custodia y el Convenio de La Haya sobre la Protecci\u00f3n de los Ni\u00f1os tambi\u00e9n <strong>permiten la ejecuci\u00f3n de las <\/strong>decisiones de contacto en el extranjero, <strong>adem\u00e1s del reconocimiento.<\/strong><\/li><\/ul>\n\n\n\n<div class=\"wp-block-group is-style-infobox is-layout-flow wp-block-group-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Sin embargo, desde el reglamento de la UE &#8220;Bruselas II-a&#8221;, esto <strong>solo ha sido relevante desde la <\/strong>perspectiva alemana <strong>en relaci\u00f3n con una serie de estados individuales<\/strong>. Estos Estados forman parte&#8230;<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>para el Convenio Europeo de Custodia: Dinamarca, Islandia, Liechtenstein, la Antigua Rep\u00fablica Yugoslava de Macedonia del Norte, Moldavia, Montenegro, Noruega, Suiza, Serbia, Turqu\u00eda y Ucrania;Moldau, Monte\u00adnegro, Norwegen, Schweiz, Serbien, die T\u00fcrkei und Ukraine;<\/li><li>para el Convenio de La Haya sobre la protecci\u00f3n de los ni\u00f1os: Dinamarca, Montenegro, Noruega, Suiza, Serbia, Turqu\u00eda y Ucrania (a partir de 2021).<\/li><\/ul>\n<\/div>\n\n\n\n<ul class=\"wp-block-list\"><li>En caso de que uno de los progenitores no cumpla con una decisi\u00f3n sobre el derecho de visita, la <strong>solicitud de &#8220;declaraci\u00f3n de ejecutoriedad&#8221; descrita <\/strong>anteriormente es posible en estos estados sobre la base del Convenio Europeo sobre la Custodia o el Convenio de La Haya sobre la Protecci\u00f3n de los Ni\u00f1os. Estaremos encantados de explicarle detalladamente las diferencias entre las normativas.<\/li><li>El Convenio Europeo sobre la Custodia y el Convenio de La Haya sobre la Protecci\u00f3n de los Ni\u00f1os no se sustituyen entre s\u00ed, sino que, por lo general, pueden aplicarse<strong> conjuntamente.<\/strong><\/li><li><strong>Una caracter\u00edstica especial del Convenio Europeo sobre la Custodia es que, si se<\/strong> ha denegado el reconocimiento o la declaraci\u00f3n de ejecutoriedad de una decisi\u00f3n sobre el derecho de visita en un Estado contratante, la Autoridad Central de ese Estado puede iniciar un procedimiento con el fin de obtener una nueva decisi\u00f3n. Esto tambi\u00e9n se aplica si hasta la fecha no ha habido ninguna decisi\u00f3n judicial sobre el derecho de acceso.<\/li><\/ul>\n<\/div><\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Si desea m\u00e1s informaci\u00f3n y una <strong>evaluaci\u00f3n de su situaci\u00f3n individual en el marco de las disposiciones legales (inter)nacionales pertinentes, <\/strong>p\u00f3ngase en contacto con nosotros para que le asesoremos.<\/p>\n\n\n\n<div class=\"wp-block-group alignfull has-primary-light-background-color has-background is-layout-constrained wp-container-core-group-is-layout-38fc762d wp-block-group-is-layout-constrained\" style=\"padding-top:70px;padding-bottom:70px\">\n<div class=\"wp-block-columns is-style-default is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-style-card is-layout-flow wp-block-group-is-layout-flow\" style=\"padding-top:26px\">\n<h3 class=\"wp-block-heading\" style=\"margin-bottom:15px\">Buscar persona de contacto<\/h3>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link\" href=\"https:\/\/zank.de\/en\/materials-addresses\/contacts\/\">Directorio de direcciones<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-style-card is-layout-flow wp-block-group-is-layout-flow\" style=\"padding-top:26px\">\n<h3 class=\"wp-block-heading\" style=\"margin-bottom:15px\">Contacte co<\/h3>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link\" href=\"https:\/\/zank.de\/es\/contacto-su-camino-hacia-el-asesoramiento\/\">A la consulta<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-style-card is-layout-flow wp-block-group-is-layout-flow\" style=\"padding-top:26px\">\n<h3 class=\"wp-block-heading\" style=\"margin-bottom:15px\">Por qu\u00e9 ZAnK<\/h3>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link\" href=\"https:\/\/zank.de\/es\/sobre-nosotros\/nuestra-oferta\/\">Nuestra oferta<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Los ni\u00f1os tienen derecho a tener contacto con ambos padres. Por el contrario, ambos progenitores tienen el derecho -y el deber- fundamental de tener contacto con su hijo. El contacto se traduce en reuniones personales peri\u00f3dicas, as\u00ed como en contactos por carta y\/o por tel\u00e9fono. Un buen acuerdo de contacto puede dar al ni\u00f1o la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":2941,"menu_order":2,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-4757","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Derecho de acceso &#8226; ZAnK<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zank.de\/es\/ayuda-con\/derecho-de-acceso\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Derecho de acceso &#8226; ZAnK\" \/>\n<meta property=\"og:description\" content=\"Los ni\u00f1os tienen derecho a tener contacto con ambos padres. Por el contrario, ambos progenitores tienen el derecho -y el deber- fundamental de tener contacto con su hijo. El contacto se traduce en reuniones personales peri\u00f3dicas, as\u00ed como en contactos por carta y\/o por tel\u00e9fono. Un buen acuerdo de contacto puede dar al ni\u00f1o la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zank.de\/es\/ayuda-con\/derecho-de-acceso\/\" \/>\n<meta property=\"og:site_name\" content=\"ZAnK\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-02T13:20:03+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/zank.de\\\/es\\\/ayuda-con\\\/derecho-de-acceso\\\/\",\"url\":\"https:\\\/\\\/zank.de\\\/es\\\/ayuda-con\\\/derecho-de-acceso\\\/\",\"name\":\"Derecho de acceso &#8226; ZAnK\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zank.de\\\/#website\"},\"datePublished\":\"2021-10-04T08:08:18+00:00\",\"dateModified\":\"2022-03-02T13:20:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zank.de\\\/es\\\/ayuda-con\\\/derecho-de-acceso\\\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/zank.de\\\/es\\\/ayuda-con\\\/derecho-de-acceso\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zank.de\\\/es\\\/ayuda-con\\\/derecho-de-acceso\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/zank.de\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ayuda con&#8230;\",\"item\":\"https:\\\/\\\/zank.de\\\/es\\\/ayuda-con\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Derecho de acceso\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zank.de\\\/#website\",\"url\":\"https:\\\/\\\/zank.de\\\/\",\"name\":\"ZAnK\",\"description\":\"Zentrale Anlaufstelle f\u00fcr grenz\u00fcberschreitende Kindschaftskonflikte und Mediation\",\"publisher\":{\"@id\":\"https:\\\/\\\/zank.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zank.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/zank.de\\\/#organization\",\"name\":\"ZAnK\",\"url\":\"https:\\\/\\\/zank.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/zank.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/zank.de\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/ZANK_Logo.svg\",\"contentUrl\":\"https:\\\/\\\/zank.de\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/ZANK_Logo.svg\",\"width\":567,\"height\":172,\"caption\":\"ZAnK\"},\"image\":{\"@id\":\"https:\\\/\\\/zank.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Derecho de acceso &#8226; ZAnK","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zank.de\/es\/ayuda-con\/derecho-de-acceso\/","og_locale":"es_ES","og_type":"article","og_title":"Derecho de acceso &#8226; ZAnK","og_description":"Los ni\u00f1os tienen derecho a tener contacto con ambos padres. Por el contrario, ambos progenitores tienen el derecho -y el deber- fundamental de tener contacto con su hijo. El contacto se traduce en reuniones personales peri\u00f3dicas, as\u00ed como en contactos por carta y\/o por tel\u00e9fono. Un buen acuerdo de contacto puede dar al ni\u00f1o la [&hellip;]","og_url":"https:\/\/zank.de\/es\/ayuda-con\/derecho-de-acceso\/","og_site_name":"ZAnK","article_modified_time":"2022-03-02T13:20:03+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"11 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/zank.de\/es\/ayuda-con\/derecho-de-acceso\/","url":"https:\/\/zank.de\/es\/ayuda-con\/derecho-de-acceso\/","name":"Derecho de acceso &#8226; ZAnK","isPartOf":{"@id":"https:\/\/zank.de\/#website"},"datePublished":"2021-10-04T08:08:18+00:00","dateModified":"2022-03-02T13:20:03+00:00","breadcrumb":{"@id":"https:\/\/zank.de\/es\/ayuda-con\/derecho-de-acceso\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/zank.de\/es\/ayuda-con\/derecho-de-acceso\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/zank.de\/es\/ayuda-con\/derecho-de-acceso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/zank.de\/es\/"},{"@type":"ListItem","position":2,"name":"Ayuda con&#8230;","item":"https:\/\/zank.de\/es\/ayuda-con\/"},{"@type":"ListItem","position":3,"name":"Derecho de acceso"}]},{"@type":"WebSite","@id":"https:\/\/zank.de\/#website","url":"https:\/\/zank.de\/","name":"ZAnK","description":"Zentrale Anlaufstelle f\u00fcr grenz\u00fcberschreitende Kindschaftskonflikte und Mediation","publisher":{"@id":"https:\/\/zank.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zank.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/zank.de\/#organization","name":"ZAnK","url":"https:\/\/zank.de\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/zank.de\/#\/schema\/logo\/image\/","url":"https:\/\/zank.de\/wp-content\/uploads\/2021\/10\/ZANK_Logo.svg","contentUrl":"https:\/\/zank.de\/wp-content\/uploads\/2021\/10\/ZANK_Logo.svg","width":567,"height":172,"caption":"ZAnK"},"image":{"@id":"https:\/\/zank.de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/zank.de\/es\/wp-json\/wp\/v2\/pages\/4757","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zank.de\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/zank.de\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/zank.de\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zank.de\/es\/wp-json\/wp\/v2\/comments?post=4757"}],"version-history":[{"count":4,"href":"https:\/\/zank.de\/es\/wp-json\/wp\/v2\/pages\/4757\/revisions"}],"predecessor-version":[{"id":4958,"href":"https:\/\/zank.de\/es\/wp-json\/wp\/v2\/pages\/4757\/revisions\/4958"}],"up":[{"embeddable":true,"href":"https:\/\/zank.de\/es\/wp-json\/wp\/v2\/pages\/2941"}],"wp:attachment":[{"href":"https:\/\/zank.de\/es\/wp-json\/wp\/v2\/media?parent=4757"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}