{"id":3869,"date":"2021-12-16T13:35:45","date_gmt":"2021-12-16T12:35:45","guid":{"rendered":"https:\/\/zank.de\/contact\/aussenstelle-wangen\/"},"modified":"2022-06-16T02:00:06","modified_gmt":"2022-06-16T00:00:06","slug":"aussenstelle-wangen","status":"publish","type":"contact","link":"https:\/\/zank.de\/en\/contact\/aussenstelle-wangen\/","title":{"rendered":"Jugendamt Ravensburg \u2013 Au\u00dfenstelle Wangen"},"content":{"rendered":"","protected":false},"parent":0,"template":"","contact-function":[36],"contact-language":[5],"contact-country":[1159],"class_list":["post-3869","contact","type-contact","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jugendamt Ravensburg \u2013 Au\u00dfenstelle Wangen &#8226; ZAnK<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zank.de\/ansprechpartner\/aussenstelle-wangen\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jugendamt Ravensburg \u2013 Au\u00dfenstelle Wangen &#8226; ZAnK\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zank.de\/ansprechpartner\/aussenstelle-wangen\/\" \/>\n<meta property=\"og:site_name\" content=\"ZAnK\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-16T00:00:06+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/zank.de\\\/ansprechpartner\\\/aussenstelle-wangen\\\/\",\"url\":\"https:\\\/\\\/zank.de\\\/ansprechpartner\\\/aussenstelle-wangen\\\/\",\"name\":\"Jugendamt Ravensburg \u2013 Au\u00dfenstelle Wangen &#8226; ZAnK\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zank.de\\\/#website\"},\"datePublished\":\"2021-12-16T12:35:45+00:00\",\"dateModified\":\"2022-06-16T00:00:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zank.de\\\/ansprechpartner\\\/aussenstelle-wangen\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/zank.de\\\/ansprechpartner\\\/aussenstelle-wangen\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zank.de\\\/ansprechpartner\\\/aussenstelle-wangen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/zank.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jugendamt Ravensburg \u2013 Au\u00dfenstelle Wangen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zank.de\\\/#website\",\"url\":\"https:\\\/\\\/zank.de\\\/\",\"name\":\"ZAnK\",\"description\":\"Zentrale Anlaufstelle f\u00fcr grenz\u00fcberschreitende Kindschaftskonflikte und Mediation\",\"publisher\":{\"@id\":\"https:\\\/\\\/zank.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zank.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/zank.de\\\/#organization\",\"name\":\"ZAnK\",\"url\":\"https:\\\/\\\/zank.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/zank.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/zank.de\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/ZANK_Logo.svg\",\"contentUrl\":\"https:\\\/\\\/zank.de\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/ZANK_Logo.svg\",\"width\":567,\"height\":172,\"caption\":\"ZAnK\"},\"image\":{\"@id\":\"https:\\\/\\\/zank.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jugendamt Ravensburg \u2013 Au\u00dfenstelle Wangen &#8226; ZAnK","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zank.de\/ansprechpartner\/aussenstelle-wangen\/","og_locale":"en_US","og_type":"article","og_title":"Jugendamt Ravensburg \u2013 Au\u00dfenstelle Wangen &#8226; ZAnK","og_url":"https:\/\/zank.de\/ansprechpartner\/aussenstelle-wangen\/","og_site_name":"ZAnK","article_modified_time":"2022-06-16T00:00:06+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/zank.de\/ansprechpartner\/aussenstelle-wangen\/","url":"https:\/\/zank.de\/ansprechpartner\/aussenstelle-wangen\/","name":"Jugendamt Ravensburg \u2013 Au\u00dfenstelle Wangen &#8226; ZAnK","isPartOf":{"@id":"https:\/\/zank.de\/#website"},"datePublished":"2021-12-16T12:35:45+00:00","dateModified":"2022-06-16T00:00:06+00:00","breadcrumb":{"@id":"https:\/\/zank.de\/ansprechpartner\/aussenstelle-wangen\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/zank.de\/ansprechpartner\/aussenstelle-wangen\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/zank.de\/ansprechpartner\/aussenstelle-wangen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/zank.de\/en\/"},{"@type":"ListItem","position":2,"name":"Jugendamt Ravensburg \u2013 Au\u00dfenstelle Wangen"}]},{"@type":"WebSite","@id":"https:\/\/zank.de\/#website","url":"https:\/\/zank.de\/","name":"ZAnK","description":"Zentrale Anlaufstelle f\u00fcr grenz\u00fcberschreitende Kindschaftskonflikte und Mediation","publisher":{"@id":"https:\/\/zank.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zank.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/zank.de\/#organization","name":"ZAnK","url":"https:\/\/zank.de\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/zank.de\/#\/schema\/logo\/image\/","url":"https:\/\/zank.de\/wp-content\/uploads\/2021\/10\/ZANK_Logo.svg","contentUrl":"https:\/\/zank.de\/wp-content\/uploads\/2021\/10\/ZANK_Logo.svg","width":567,"height":172,"caption":"ZAnK"},"image":{"@id":"https:\/\/zank.de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/zank.de\/en\/wp-json\/wp\/v2\/contact\/3869","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zank.de\/en\/wp-json\/wp\/v2\/contact"}],"about":[{"href":"https:\/\/zank.de\/en\/wp-json\/wp\/v2\/types\/contact"}],"wp:attachment":[{"href":"https:\/\/zank.de\/en\/wp-json\/wp\/v2\/media?parent=3869"}],"wp:term":[{"taxonomy":"contact-function","embeddable":true,"href":"https:\/\/zank.de\/en\/wp-json\/wp\/v2\/contact-function?post=3869"},{"taxonomy":"contact-language","embeddable":true,"href":"https:\/\/zank.de\/en\/wp-json\/wp\/v2\/contact-language?post=3869"},{"taxonomy":"contact-country","embeddable":true,"href":"https:\/\/zank.de\/en\/wp-json\/wp\/v2\/contact-country?post=3869"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}